{"id":1029,"date":"2019-10-14T17:58:03","date_gmt":"2019-10-14T15:58:03","guid":{"rendered":"https:\/\/www.bancoboveri.com\/shop\/?p=1029"},"modified":"2019-12-05T07:47:12","modified_gmt":"2019-12-05T06:47:12","slug":"creare-vero-rame-ossidato-su-superfici-metalliche-ossidabili-e-legno-ricco-di-tannino","status":"publish","type":"post","link":"https:\/\/www.bancoboveri.com\/shop\/guide\/ossidazioni\/creare-vero-rame-ossidato-su-superfici-metalliche-ossidabili-e-legno-ricco-di-tannino\/","title":{"rendered":"Creare vero rame ossidato su superfici metalliche ossidabili e legno ricco di tannino"},"content":{"rendered":"<blockquote><p><span style=\"color: #008000;\"><span style=\"color: #339966;\">Creare vero rame ossidato su superfici metalliche ossidabili (escluso inox e zincate) e legno ricco di tannino* con un ciclo a base d&#8217;acqua senza usare prodotti corrosivi e acidi pericolosi.<\/span><br \/>\n<\/span><\/p><\/blockquote>\n<p><span style=\"color: #008000;\"><strong><a href=\"https:\/\/www.bancoboveri.com\/shop\/wp-content\/uploads\/2019\/07\/gl-ME-Hilltop-Cleaners-lrg.jpg\"><img loading=\"lazy\" decoding=\"async\" class=\"wp-image-1026 size-thumbnail alignleft\" src=\"https:\/\/www.bancoboveri.com\/shop\/wp-content\/uploads\/2019\/07\/gl-ME-Hilltop-Cleaners-lrg-150x150.jpg\" alt=\"\" width=\"150\" height=\"150\" srcset=\"https:\/\/www.bancoboveri.com\/shop\/wp-content\/uploads\/2019\/07\/gl-ME-Hilltop-Cleaners-lrg-150x150.jpg 150w, https:\/\/www.bancoboveri.com\/shop\/wp-content\/uploads\/2019\/07\/gl-ME-Hilltop-Cleaners-lrg-300x300.jpg 300w, https:\/\/www.bancoboveri.com\/shop\/wp-content\/uploads\/2019\/07\/gl-ME-Hilltop-Cleaners-lrg-100x100.jpg 100w, https:\/\/www.bancoboveri.com\/shop\/wp-content\/uploads\/2019\/07\/gl-ME-Hilltop-Cleaners-lrg-400x400.jpg 400w, https:\/\/www.bancoboveri.com\/shop\/wp-content\/uploads\/2019\/07\/gl-ME-Hilltop-Cleaners-lrg-305x305.jpg 305w, https:\/\/www.bancoboveri.com\/shop\/wp-content\/uploads\/2019\/07\/gl-ME-Hilltop-Cleaners-lrg-144x144.jpg 144w\" sizes=\"auto, (max-width: 150px) 100vw, 150px\" \/><\/a><\/strong><\/span>Il ciclo \u00e8 composto da <a href=\"https:\/\/www.bancoboveri.com\/shop\/prodotto\/creare-ruggine-su-cor-ten-ferro-e-lamierino\/\"><span style=\"color: #339966;\"><strong>4 prodotti a base d&#8217;acqua<\/strong><\/span><\/a>:<br \/>\n\u2013 il fondo a base d&#8217;acqua <a href=\"https:\/\/www.bancoboveri.com\/shop\/prodotto\/effect-primer\/\">Effect Primer<\/a><br \/>\n\u2013 il metallo liquido <a href=\"https:\/\/www.bancoboveri.com\/shop\/prodotto\/vero-rame-effect-copper-paint\/\">Effect Copper Paint &#8211; Vero Rame<\/a><br \/>\n\u2013 la patina tradizionale <a href=\"https:\/\/www.bancoboveri.com\/shop\/prodotto\/patina-ossido-verde-effect-patina-green\/\" target=\"_blank\" rel=\"noopener noreferrer\">Effect Green Patina<\/a> oppure la pi\u00f9 chiara <a href=\"https:\/\/www.bancoboveri.com\/shop\/prodotto\/patina-ossido-blu-effect-patina-blue\/\">Effect Blue Patina<\/a><br \/>\n\u2013 in opzione il protettivo <a href=\"https:\/\/www.bancoboveri.com\/shop\/prodotto\/effect-sealer\/\" target=\"_blank\" rel=\"noopener noreferrer\">Effect Sealer<\/a><\/p>\n<p>E\u2019 disponibile anche il rullo in spugna naturale <strong>Sponge Roller <\/strong>per creare macchiature di patinatura irregolari e differenti<\/p>\n<p><!--more--><\/p>\n<p><em><span style=\"color: #008000;\">*tutte le altre superfici pitturabili, comprese inox e zincate, devono essere trattate con <a href=\"https:\/\/www.bancoboveri.com\/shop\/ossidazioni\/creare-vero-rame-ossidato-su-qualsiasi-superficie-pitturabile\/\">altro primer (vedere qui)<\/a><\/span><\/em><\/p>\n<h4 style=\"text-align: center;\">COME PREPARARE LA SUPERFICIE<\/h4>\n<p>Pulire perfettamente la superficie rimuovendo grasso, sporco e precedenti finiture in cattivo stato. Per superfici metalliche assicurarsi che non ci sia un processo ossidativo in atto, nel caso procedere con <a href=\"https:\/\/www.bancoboveri.com\/shop\/prodotto\/rustyco\/\">Rustyco GEL<\/a> oppure carteggiare.<\/p>\n<blockquote>\n<p style=\"text-align: left;\"><span style=\"color: #339966;\">Ricorda che la pulizia e la preparazione accurata delle superfici ti permettono di far ancorare bene la finitura e ottenere il miglior risultato<\/span><\/p>\n<\/blockquote>\n<h4 style=\"text-align: center;\">COME APPLICARE IL PRIMER E IL METALLO LIQUIDO<\/h4>\n<p>Applicare fino ad un massino di 2 mani di <a href=\"https:\/\/www.bancoboveri.com\/shop\/prodotto\/effect-primer\/\">Effect Primer<\/a> lasciando asciugare almeno 2 ore tra una mano e l&#8217;altra. Lasciare essiccare l&#8217;ultima mano almeno 12 ore. Applicare al massimo 3 mani incrociate a pennello o a rullo pelo corto, a distanza di almeno 2 ore una dall&#8217;altra, di <a href=\"https:\/\/www.bancoboveri.com\/shop\/prodotto\/vero-rame-effect-copper-paint\/\">Effect Copper Paint &#8211; Vero Rame<\/a>. Se si desidera ossidare procedere entro 5 minuti dall&#8217;ultima mano applicata di\u00a0<a href=\"https:\/\/www.bancoboveri.com\/shop\/prodotto\/vero-rame-effect-copper-paint\/\">Effect Copper Paint &#8211; Vero Rame<\/a> con la patina tradizionale <a href=\"https:\/\/www.bancoboveri.com\/shop\/prodotto\/patina-ossido-verde-effect-patina-green\/\" target=\"_blank\" rel=\"noopener noreferrer\">Effect Green Patina<\/a> oppure la pi\u00f9 chiara <a href=\"https:\/\/www.bancoboveri.com\/shop\/prodotto\/patina-ossido-blu-effect-patina-blue\/\">Effect Blue Patina<\/a><\/p>\n<blockquote><p><span style=\"color: #339966;\"><strong>Nota bene:<\/strong> alcune superfici metalliche (carrozzeria, serbatoi, ecc&#8230;) e cementizie (resinature, cementi liquidi decorativi, ecc&#8230;) potrebbero necessitare di una preparazione aggiuntiva &#8211; chiedi informazioni aggiuntive ai nostri tecnici<\/span><\/p><\/blockquote>\n<h4 style=\"text-align: center;\">COME CREARE LA PATINA OSSIDATIVA<\/h4>\n<p style=\"text-align: left;\">Applicare <a href=\"https:\/\/www.bancoboveri.com\/shop\/prodotto\/patina-ossido-verde-effect-patina-green\/\" target=\"_blank\" rel=\"noopener noreferrer\">Effect Green Patina<\/a> o <a href=\"https:\/\/www.bancoboveri.com\/shop\/prodotto\/patina-ossido-blu-effect-patina-blue\/\">Effect Blue Patina<\/a> in non pi\u00f9 di tre mani ad intervalli da 5 a 40 minuti una dall&#8217;altra a seconda del risultato che si vuole ottenere. Lasciare essiccare per 24 ore prima di procedere ad una eventuale protezione. L&#8217;esposizione a fonti di calore (raggi solari, stufetta, phon) e il quantitativo di prodotto applicato sulla superficie condizionano la colorazione finale dell&#8217;ossidazione.<\/p>\n<blockquote><p><span style=\"color: #339966;\">Sfrutta le potenzialit\u00e0 della confezione a spruzzo che vaporizza finemente il prodotto oppure usa una spugna naturale, pennello, rullo, straccio utilizzando stencil e dime per creare una ossidazione personalizzata<\/span><\/p><\/blockquote>\n<div class=\"post-video\"><iframe loading=\"lazy\" title=\"Modern Masters Metal Effects\u00ae Green Patina Finish How-to\" width=\"1165\" height=\"655\" src=\"https:\/\/www.youtube.com\/embed\/whWK3LQ6L8E?feature=oembed\" frameborder=\"0\" allow=\"accelerometer; autoplay; encrypted-media; gyroscope; picture-in-picture\" allowfullscreen><\/iframe><\/div>\n<h4 style=\"text-align: center;\">PROTEGGERE LA PATINA OSSIDATIVA<\/h4>\n<p style=\"text-align: left;\">Per evitare che la patina progredisca, specie in esterno, o spolveri sugli oggetti o sulle mani, si pu\u00f2 applicare sull&#8217;ossidazione creata <a href=\"https:\/\/www.bancoboveri.com\/shop\/prodotto\/effect-sealer\/\" target=\"_blank\" rel=\"noopener noreferrer\">Effect Sealer<\/a>. <a href=\"https:\/\/www.bancoboveri.com\/shop\/prodotto\/effect-sealer\/\" target=\"_blank\" rel=\"noopener noreferrer\">Effect Sealer<\/a> ha una buona resistenza alla manipolazione, al graffio e al moderato calpestio (oltre 3.000 spazzolature) e si pu\u00f2 utilizzare sia per interni che esterno e in ambienti umidi. La finitura varia da opaca a satinata lucida a seconda del numero di mani. La prima mano obbligatoriamente diluita 1:1 con acqua naturale o distillata. Applicare fino a 3 mani di <a href=\"https:\/\/www.bancoboveri.com\/shop\/prodotto\/effect-sealer\/\" target=\"_blank\" rel=\"noopener noreferrer\">Effect Sealer<\/a> (4 se applicate a spruzzo HVLP) lasciando asciugare 2 ore tra una mano e l\u2019altra. Essiccazione completa dopo 24 ore. Calpestabile moderatamente dopo 3 giorni.<br \/>\nDurata indicativa della protezione fino a 3 anni a seconda di superficie, metodo applicativo, numero di mani, condizioni climatiche e condizioni di utilizzo.<\/p>\n<blockquote><p><span style=\"color: #339966;\">Se utilizzi Effect Sealer diluito per tutte le mani che vuoi applicare otterrai una superficie da opaca a satinata opaca ma con una resistenza inferiore agli agenti atmosferici e a manipolazione e sfregamento.<\/span><\/p><\/blockquote>\n<h4 style=\"text-align: center;\">ULTERIORI INFORMAZIONI<\/h4>\n<p>TEMPERATURA IDEALE PER L\u2019APPLICAZIONE: da 16\u00b0C a 32\u00b0C, l\u2019umidit\u00e0 condiziona fortemente i risultati. Non applicare e non far essiccare il prodotto <a href=\"https:\/\/www.bancoboveri.com\/shop\/prodotto\/effect-sealer\/\" target=\"_blank\" rel=\"noopener noreferrer\">Effect Sealer<\/a> in presenza di forte umidit\u00e0 (&gt;80%) e a temperatura ambientale al di sotto dei 16\u00b0C.<br \/>\nMANUTENZIONE: il manufatto con il tempo tender\u00e0 a perdere l\u2019effetto protettivo. Applicare una o pi\u00f9 mani di <a href=\"https:\/\/www.bancoboveri.com\/shop\/prodotto\/effect-sealer\/\" target=\"_blank\" rel=\"noopener noreferrer\">Effect Sealer<\/a> su superficie asciutta e pulita (priva di sporco, grasso, ecc\u2026) e lasciare asciugare.<\/p>\n<h4 style=\"text-align: center;\">INFORMAZIONI DI GARANZIA<\/h4>\n<p style=\"text-align: left;\">E\u2019 stata prestata massima cura affinch\u00e9 le informazioni contenute in questo protocollo siano accurate. Boveri srl non pu\u00f2 garantire alcun risultato in quanto non ha alcun controllo sulle condizioni, applicazioni, tecniche e superfici sulle quali i prodotti vengono impiegati. Le informazioni qui presenti non implicano la responsabilit\u00e0 della Boveri srl, non essendo l\u2019applicazione dei prodotti svolta sotto il suo controllo.<\/p>\n","protected":false},"excerpt":{"rendered":"<p>Creare vero rame ossidato su superfici metalliche ossidabili (escluso inox e zincate) e legno ricco di tannino* con un ciclo a base d&#8217;acqua senza usare prodotti corrosivi e acidi pericolosi. Il ciclo \u00e8 composto da 4 prodotti a base d&#8217;acqua: \u2013 il fondo a base d&#8217;acqua Effect Primer \u2013 il metallo liquido Effect Copper Paint [&hellip;]<\/p>\n","protected":false},"author":1,"featured_media":1026,"comment_status":"closed","ping_status":"open","sticky":false,"template":"","format":"standard","meta":{"_seopress_robots_primary_cat":"","_seopress_titles_title":"","_seopress_titles_desc":"","_seopress_robots_index":"","_joinchat":[],"footnotes":""},"categories":[108,72],"tags":[],"class_list":["post-1029","post","type-post","status-publish","format-standard","has-post-thumbnail","hentry","category-guide","category-ossidazioni","has-post-title","has-post-date","has-post-category","has-post-tag","has-post-comment","has-post-author",""],"_links":{"self":[{"href":"https:\/\/www.bancoboveri.com\/shop\/wp-json\/wp\/v2\/posts\/1029","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/www.bancoboveri.com\/shop\/wp-json\/wp\/v2\/posts"}],"about":[{"href":"https:\/\/www.bancoboveri.com\/shop\/wp-json\/wp\/v2\/types\/post"}],"author":[{"embeddable":true,"href":"https:\/\/www.bancoboveri.com\/shop\/wp-json\/wp\/v2\/users\/1"}],"replies":[{"embeddable":true,"href":"https:\/\/www.bancoboveri.com\/shop\/wp-json\/wp\/v2\/comments?post=1029"}],"version-history":[{"count":0,"href":"https:\/\/www.bancoboveri.com\/shop\/wp-json\/wp\/v2\/posts\/1029\/revisions"}],"wp:featuredmedia":[{"embeddable":true,"href":"https:\/\/www.bancoboveri.com\/shop\/wp-json\/wp\/v2\/media\/1026"}],"wp:attachment":[{"href":"https:\/\/www.bancoboveri.com\/shop\/wp-json\/wp\/v2\/media?parent=1029"}],"wp:term":[{"taxonomy":"category","embeddable":true,"href":"https:\/\/www.bancoboveri.com\/shop\/wp-json\/wp\/v2\/categories?post=1029"},{"taxonomy":"post_tag","embeddable":true,"href":"https:\/\/www.bancoboveri.com\/shop\/wp-json\/wp\/v2\/tags?post=1029"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}